{"id":3268,"date":"2020-07-06T11:20:27","date_gmt":"2020-07-06T11:20:27","guid":{"rendered":"https:\/\/andaluciadestinodecine.com\/?post_type=pelicula&#038;p=3268"},"modified":"2020-07-06T11:20:27","modified_gmt":"2020-07-06T11:20:27","slug":"isabel","status":"publish","type":"pelicula","link":"https:\/\/andaluciadestinodecine.com\/en\/pelicula\/isabel\/","title":{"rendered":"Isabel"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-3268","pelicula","type-pelicula","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/pelicula\/3268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/pelicula"}],"about":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/types\/pelicula"}],"version-history":[{"count":0,"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/pelicula\/3268\/revisions"}],"wp:attachment":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/media?parent=3268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}