{"id":4822,"date":"2020-07-13T10:31:13","date_gmt":"2020-07-13T10:31:13","guid":{"rendered":"https:\/\/andaluciadestinodecine.com\/pelicula\/el-abominable-hombre-de-la-costa-del-sol\/"},"modified":"2020-09-07T14:00:40","modified_gmt":"2020-09-07T12:00:40","slug":"el-abominable-hombre-de-la-costa-del-sol","status":"publish","type":"pelicula","link":"https:\/\/andaluciadestinodecine.com\/en\/pelicula\/el-abominable-hombre-de-la-costa-del-sol\/","title":{"rendered":"El abominable hombre de la Costa del Sol"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-4822","pelicula","type-pelicula","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/pelicula\/4822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/pelicula"}],"about":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/types\/pelicula"}],"version-history":[{"count":0,"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/pelicula\/4822\/revisions"}],"wp:attachment":[{"href":"https:\/\/andaluciadestinodecine.com\/en\/wp-json\/wp\/v2\/media?parent=4822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}